{"id":4876,"date":"2025-02-04T13:54:34","date_gmt":"2025-02-04T16:54:34","guid":{"rendered":"https:\/\/tiemponoticias.com.ar\/noticias\/?p=4876"},"modified":"2025-02-04T13:54:34","modified_gmt":"2025-02-04T16:54:34","slug":"%f0%9f%94%b4-pena-de-musica-popular-en-el-club-atletico","status":"publish","type":"post","link":"https:\/\/tiemponoticias.com.ar\/noticias\/%f0%9f%94%b4-pena-de-musica-popular-en-el-club-atletico\/","title":{"rendered":"&#x1f534; PE\u00d1A DE M\u00daSICA POPULAR EN EL CLUB ATL\u00c9TICO"},"content":{"rendered":"<p>A trav\u00e9s de #FmTiempo el presidente del club atl\u00e9tico, Miguel Curuli, detall\u00f3 c\u00f3mo se llevar\u00e1 adelante la pe\u00f1a de m\u00fasica popular este viernes a las 21:00hs.<\/p>\n<p>\u201cLa pe\u00f1a va abrir sus puertas a las 20:30hs y el arranque va a ser a partir de las 21:00hs\u201d.<\/p>\n<p>\u201cLa entrada va a ser por Bulnes y se va hacer en el predio atr\u00e1s del arco de la cancha Asali\u201d.<\/p>\n<p>\u201cVa a haber mesas, cantina, la gente solo va a tener que ir a disfrutar\u201d,<\/p>\n<p>\u201cLa entrada anticipada va a estar $5.000 que se van a estar vendiendo hasta el viernes al mediod\u00eda y en puerta va a estar $6.000\u201d.<\/p>\n<p>\u201cTodo lo recaudado va para el club para hacer obras en el club\u201d.<\/p>\n<p>\u201cSe nos ocurri\u00f3 la idea en el marco de los 50 a\u00f1os del festival\u201d.<\/p>\n<p>Tiemponoticias.com.ar<\/p>\n<p>Www.Tiemponoticias.com.ar<\/p>\n<p>Noticias Baradero<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A trav\u00e9s de #FmTiempo el presidente del club atl\u00e9tico, Miguel Curuli, detall\u00f3 c\u00f3mo se llevar\u00e1 adelante la pe\u00f1a de m\u00fasica popular este viernes a las 21:00hs. \u201cLa pe\u00f1a va abrir sus puertas a las 20:30hs y el arranque va a ser a partir de las 21:00hs\u201d. \u201cLa entrada va a ser por Bulnes y se [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":4877,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[61],"class_list":["post-4876","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-principal"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/tiemponoticias.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/4876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tiemponoticias.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tiemponoticias.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tiemponoticias.com.ar\/noticias\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/tiemponoticias.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=4876"}],"version-history":[{"count":1,"href":"https:\/\/tiemponoticias.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/4876\/revisions"}],"predecessor-version":[{"id":4878,"href":"https:\/\/tiemponoticias.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/4876\/revisions\/4878"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tiemponoticias.com.ar\/noticias\/wp-json\/wp\/v2\/media\/4877"}],"wp:attachment":[{"href":"https:\/\/tiemponoticias.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=4876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tiemponoticias.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=4876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tiemponoticias.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=4876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}