{"id":4651,"date":"2025-01-20T11:48:36","date_gmt":"2025-01-20T14:48:36","guid":{"rendered":"https:\/\/tiemponoticias.com.ar\/noticias\/?p=4651"},"modified":"2025-01-20T11:48:36","modified_gmt":"2025-01-20T14:48:36","slug":"se-quemo-una-heladera-del-cic-entonces-la-reemplazamos-por-la-de-uso-personal-de-la-sala-astigueta","status":"publish","type":"post","link":"https:\/\/tiemponoticias.com.ar\/noticias\/se-quemo-una-heladera-del-cic-entonces-la-reemplazamos-por-la-de-uso-personal-de-la-sala-astigueta\/","title":{"rendered":"\u201cSE QUEM\u00d3 UNA HELADERA DEL CIC ENTONCES LA REEMPLAZAMOS POR LA DE USO PERSONAL DE LA SALA ASTIGUETA\u201d"},"content":{"rendered":"<p>Lo manifest\u00f3 en #FmTiempo Sala Astigueta el Director de Atenci\u00f3n M\u00e9dica de la Salud, Marcelo Elmer, al ser consultado por la falta de una heladera en la sala Astigueta.<\/p>\n<p>\u201cTenemos heladera en todas las salas\u201d.<\/p>\n<p>\u201cAh\u00ed hab\u00eda dos heladera, una se usaba para las vacunas y otra para el personal<\/p>\n<p>\u201cHace una semana y media o dos semanas se quem\u00f3 una heladera del cic entonces sacamos la del uso personal de la sala Astigueta y luego cuando se arregle se devuelve\u201d.<\/p>\n<p>Tiemponoticias.com.ar<\/p>\n<p>Www.Tiemponoticias.com.ar<\/p>\n<p>Noticias Baradero<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo manifest\u00f3 en #FmTiempo Sala Astigueta el Director de Atenci\u00f3n M\u00e9dica de la Salud, Marcelo Elmer, al ser consultado por la falta de una heladera en la sala Astigueta. \u201cTenemos heladera en todas las salas\u201d. \u201cAh\u00ed hab\u00eda dos heladera, una se usaba para las vacunas y otra para el personal \u201cHace una semana y media [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":4652,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[61],"class_list":["post-4651","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-principal"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/tiemponoticias.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/4651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tiemponoticias.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tiemponoticias.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tiemponoticias.com.ar\/noticias\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/tiemponoticias.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=4651"}],"version-history":[{"count":1,"href":"https:\/\/tiemponoticias.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/4651\/revisions"}],"predecessor-version":[{"id":4653,"href":"https:\/\/tiemponoticias.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/4651\/revisions\/4653"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tiemponoticias.com.ar\/noticias\/wp-json\/wp\/v2\/media\/4652"}],"wp:attachment":[{"href":"https:\/\/tiemponoticias.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=4651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tiemponoticias.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=4651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tiemponoticias.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=4651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}