{"id":1331,"date":"2024-05-03T15:44:36","date_gmt":"2024-05-03T15:44:36","guid":{"rendered":"https:\/\/tiemponoticias.com.ar\/noticias\/?p=1331"},"modified":"2024-05-03T15:44:36","modified_gmt":"2024-05-03T15:44:36","slug":"sanpedro-caso-nouet-aprehendieron-a-uno-de-los-sospechosos-y-esta-a-disposicion-de-la-justicia","status":"publish","type":"post","link":"https:\/\/tiemponoticias.com.ar\/noticias\/sanpedro-caso-nouet-aprehendieron-a-uno-de-los-sospechosos-y-esta-a-disposicion-de-la-justicia\/","title":{"rendered":"\u00a0#SanPedro\u00a0| CASO NOUET: APREHENDIERON A UNO DE LOS SOSPECHOSOS Y EST\u00c1 A DISPOSICI\u00d3N DE LA JUSTICIA"},"content":{"rendered":"<p>Identificado como Franco Neyra, alias \u00abEl Rosarino\u00bb, la polic\u00eda lo encontr\u00f3 en un domicilio de calle Bottaro, entre Petrona Simonino y Mart\u00edn Fierro. Adem\u00e1s, en otro procedimiento secuestraron un arma de id\u00e9nticas caracter\u00edsticas a la homicida y aprehendieron a una mujer.<br class=\"html-br\" \/><br class=\"html-br\" \/>Al respecto, por\u00a0<a class=\"x1i10hfl xjbqb8w x1ejq31n xd10rxx x1sy0etr x17r0tee x972fbf xcfux6l x1qhh985 xm0m39n x9f619 x1ypdohk xt0psk2 xe8uvvx xdj266r x11i5rnm xat24cr x1mh8g0r xexx8yu x4uap5 x18d9i69 xkhd6sd x16tdsg8 xggy1nq x1a2a7pz xt0b8zv x1hl2dhg xzsf02u x1s688f\" tabindex=\"0\" role=\"link\" href=\"https:\/\/www.facebook.com\/hashtag\/fmtiempo?__eep__=6&amp;__cft__[0]=AZXwO1HdZGZAaUYAP012-NmxW1n5VTM_W6PdW9NfOQAUwqu-qGDO3V7WNfFZEKpXRdkgdYIE-ZT7BpI4oj83cLqO9jMnuZuQoKUkdePQb4Jhrn8qzkL0Y78yrjiV1FvwnlE6PoFZBxmWUG4p4w9ywahREbekSrIb28uspj1h2h_n802qU-JGbCWHavVEaXkFdEoDdWsSWapyYtMlpSbqlIaq&amp;__tn__=*NK*F\">#FmTiempo<\/a>, la periodista de &#8216;La Radio 92.3&#8217;, Betty Rodr\u00edguez, cont\u00f3 detalles sobre el avance de la causa del asesinato de Sandra Nouet.<br class=\"html-br\" \/><br class=\"html-br\" \/>\u00abNi bien se conoci\u00f3 el asesinato que gener\u00f3 var\u00eda conmoci\u00f3n y varias versiones, a partir de los testimonios que se tom\u00f3 se realizaron ayer 7 allanamientos en distintos domicilios, se detuvo a esta persona Franco Rafael Neyra, alias \u00abEl Rosarino\u00bb es uno de los nombres que surgi\u00f3 como uno de los presuntos autores del asesinato.\u00bb<br class=\"html-br\" \/><br class=\"html-br\" \/>\u00abTodav\u00eda no tenemos bien en claro como fue la situaci\u00f3n pero todo indica sobre un ajuste de cuenta por drogas, tampoco sabemos si ese era el objetivo, ella vivia con el concubino y su hijo.\u00bb<\/p>\n<p>Tiemponoticias.com.ar<\/p>\n<p>Www.tiemponoticias.com.ar<\/p>\n<p>Noticias Baradero<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Identificado como Franco Neyra, alias \u00abEl Rosarino\u00bb, la polic\u00eda lo encontr\u00f3 en un domicilio de calle Bottaro, entre Petrona Simonino y Mart\u00edn Fierro. Adem\u00e1s, en otro procedimiento secuestraron un arma de id\u00e9nticas caracter\u00edsticas a la homicida y aprehendieron a una mujer.Al respecto, por\u00a0#FmTiempo, la periodista de &#8216;La Radio 92.3&#8217;, Betty Rodr\u00edguez, cont\u00f3 detalles sobre el [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":1332,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[175],"tags":[61],"class_list":["post-1331","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiales","tag-principal"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/tiemponoticias.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/1331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tiemponoticias.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tiemponoticias.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tiemponoticias.com.ar\/noticias\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/tiemponoticias.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=1331"}],"version-history":[{"count":1,"href":"https:\/\/tiemponoticias.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/1331\/revisions"}],"predecessor-version":[{"id":1333,"href":"https:\/\/tiemponoticias.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/1331\/revisions\/1333"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tiemponoticias.com.ar\/noticias\/wp-json\/wp\/v2\/media\/1332"}],"wp:attachment":[{"href":"https:\/\/tiemponoticias.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=1331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tiemponoticias.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=1331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tiemponoticias.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=1331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}